{"id":3186,"date":"2023-09-01T12:05:19","date_gmt":"2023-09-01T11:05:19","guid":{"rendered":"https:\/\/deltacafes.com\/?page_id=3186"},"modified":"2024-07-12T12:33:03","modified_gmt":"2024-07-12T11:33:03","slug":"angola-2","status":"publish","type":"page","link":"https:\/\/deltacafes.com\/en\/angola-2\/","title":{"rendered":"ANGOLA"},"content":{"rendered":"<style id=\"depicter-59-inline-pre-css\">\n\n.depicter-revert.depicter-59{\n\tbackground-color:#FFFFFF;\n}\n.depicter-59:not(.depicter-ready){\n\theight:100px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-59:not(.depicter-ready){\n\theight:180px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-59:not(.depicter-ready){\n\theight:100px;\n}\n\n}\n<\/style>\n<div id=\"depicter-59\" class=\"depicter depicter-document depicter-revert depicter-59 depicter-layout-fullwidth MENU\">\n\n<div class=\"depicter-loading-container depicter-loading tailSpin-dark\"><svg class=\"depicter-single-svg-loading\" viewbox=\"0 0 38 38\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n   <defs>\n      <linearGradient x1=\"8.042%\" y1=\"0%\" x2=\"65.682%\" y2=\"23.865%\" id=\"a\">\n         <stop stop-color=\"#050A0E\" stop-opacity=\"0\" offset=\"0%\" \/>\n         <stop stop-color=\"#050A0E\" stop-opacity=\".631\" offset=\"63.146%\" \/>\n         <stop stop-color=\"#050A0E\" offset=\"100%\" \/>\n      <\/linearGradient>\n   <\/defs>\n   <g fill=\"none\" fill-rule=\"evenodd\">\n      <g transform=\"translate(1 1)\">\n         <path d=\"M36 18c0-9.94-8.06-18-18-18\" id=\"Oval-2\" stroke=\"url(#a)\" stroke-width=\"2\">\n            <animateTransform attributename=\"transform\" type=\"rotate\" from=\"0 18 18\" to=\"360 18 18\" dur=\"0.9s\" repeatcount=\"indefinite\" \/>\n         <\/path>\n         <circle fill=\"#050A0E\" cx=\"36\" cy=\"18\" r=\"1\">\n            <animateTransform attributename=\"transform\" type=\"rotate\" from=\"0 18 18\" to=\"360 18 18\" dur=\"0.9s\" repeatcount=\"indefinite\" \/>\n         <\/circle>\n      <\/g>\n   <\/g>\n<\/svg>\n<\/div>\n<div id=\"depicter-59-section-27\" class=\"depicter-section depicter-59-section-27  MENU-M\" data-name=\"Slide 3\" data-type=\"section\" data-local-id=\"section-27\">\n<a href=\"https:\/\/deltacafes.com\/historia\"><button id=\"depicter-59-element-29\" class=\"depicter-element depicter-layer depicter-59-element-29\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 7\" data-local-id=\"element-29\" data-offset=\"x:129px;y:0px;origin:ml\" data-tablet-offset=\"x:188px;y:1px;origin:ml\" data-mobile-offset=\"x:-171px;y:-63px;origin:mr\" data-width=\"110px,110px,110px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\">HIST\u00d3RIA<\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/produtos\"><button id=\"depicter-59-element-30\" class=\"depicter-element depicter-layer depicter-59-element-30\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 8\" data-local-id=\"element-30\" data-offset=\"x:222px;y:0px;origin:mc\" data-tablet-offset=\"x:-139px;y:0px;origin:mc\" data-mobile-offset=\"x:-177px;y:-174px;origin:mr\" data-width=\"169px,110px,110px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\">CONSUMO EM CASA<\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/sustentabilidade\"><button id=\"depicter-59-element-31\" class=\"depicter-element depicter-layer depicter-59-element-31\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 9\" data-local-id=\"element-31\" data-offset=\"x:-227px;y:0px;origin:mc\" data-tablet-offset=\"x:9px;y:0px;origin:ml\" data-mobile-offset=\"x:-210px;y:-364px;origin:mr\" data-width=\"158px,158px,158px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\">Sustentabilidade<\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/profissional\"><button id=\"depicter-59-element-32\" class=\"depicter-element depicter-layer depicter-59-element-32\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 10\" data-local-id=\"element-32\" data-offset=\"x:362px;y:0px;origin:mr\" data-tablet-offset=\"x:166px;y:1px;origin:mc\" data-mobile-offset=\"x:-188px;y:-275px;origin:mr\" data-width=\"158px,158px,158px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\"> Profissional<\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/contactos\"><button id=\"depicter-59-element-33\" class=\"depicter-element depicter-layer depicter-59-element-33\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 11\" data-local-id=\"element-33\" data-offset=\"x:119px;y:0px;origin:mr\" data-tablet-offset=\"x:0px;y:1px;origin:mr\" data-mobile-offset=\"x:-186px;y:-453px;origin:mr\" data-width=\"110px,110px,110px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\">Contactos <\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/delta-no-mundo\"><button id=\"depicter-59-element-34\" class=\"depicter-element depicter-layer depicter-59-element-34\" data-type=\"button\" data-wrap=\"true\" data-name=\"Button 12\" data-local-id=\"element-34\" data-offset=\"x:374px;y:0px;origin:ml\" data-tablet-offset=\"x:132px;y:1px;origin:mr\" data-mobile-offset=\"x:-188px;y:-112px;origin:mr\" data-width=\"145px,145px,145px\" data-height=\"40px,40px,40px\" data-responsive-scale=\"true,,\"><span class=\"dp-inner-content\">Delta no Mundo<\/span><\/button><\/a>\n<a href=\"https:\/\/deltacafes.com\/\">\n<picture id=\"depicter-59-element-74\" class=\"depicter-element depicter-layer depicter-59-element-74\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 10\" data-local-id=\"element-74\" data-offset=\"x:-5px;y:0px;origin:mc\" data-mobile-offset=\"x:0px;y:10px;origin:mc\" data-width=\"83px,,58px\" data-height=\"80px,,55px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO-DETA-58x55.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO-DETA-116x110.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO-DETA-83x80.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO-DETA-166x160.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO-DETA-83x80.png\" alt=\"\" \/>\n<\/picture>\n<\/a><\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/deltacafes.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-59',\n\t\t{\"width\":[\"1920\",\"1024\",\"360\"],\"height\":[\"100\",\"180\",\"100\"],\"view\":\"basic\",\"keepAspectRatio\":false,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/deltacafes.com\\\/wp-admin\\\/admin-ajax.php\",\"viewOptions\":{\"loop\":false},\"mouseSwipe\":false,\"touchSwipe\":false,\"mouseWheel\":false,\"keyboard\":false,\"fullscreenMargin\":\"0\",\"useWatermark\":false}\n\t);\n});\n<\/script>\n\n\n<style id=\"depicter-676-inline-pre-css\">\n\n.depicter-676:not(.depicter-ready){\n\theight:700px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-676:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-676:not(.depicter-ready){\n\theight:380px;\n}\n\n}\n<\/style>\n<div id=\"depicter-676\" class=\"depicter depicter-document depicter-revert depicter-676 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-676-section-1\" class=\"depicter-section depicter-676-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture id=\"depicter-676-element-5\" class=\"depicter-element depicter-layer depicter-676-element-5\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 4\" data-local-id=\"element-5\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:-359px;y:0px;origin:tl\" data-width=\"1918px,,1043px\" data-height=\"700px,,387px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/12\/baner solo angola-1043x387.jpg, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/12\/baner solo angola-2086x774.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/12\/baner solo angola-1918x700.jpg, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/12\/baner solo angola-3836x1400.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/12\/baner solo angola-1918x700.jpg\" alt=\"\" \/>\n<\/picture><\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/deltacafes.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-676',\n\t\t{\"width\":[\"1900\",\"1024\",\"360\"],\"height\":[\"700\",\"700\",\"380\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/deltacafes.com\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"everest-forms\"><script type='text\/javascript'>\n\/* <![CDATA[ *\/\nvar evf_settings = {\"currency_code\":\"EUR\",\"currency_thousands\":\".\",\"currency_decimal\":\",\",\"currency_symbol\":\"\\u20ac\",\"currency_symbol_pos\":\"right\"}\n\/* ]]> *\/\n<\/script>\n<div class=\"evf-container default\" id=\"evf-3181\"><form id=\"evf-form-3181\" class=\"everest-form\" data-formid=\"3181\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" data-form_state_type=\"\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/3186\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce3181\" name=\"_wpnonce3181\" value=\"ecb826a769\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/3186\" \/><div class=\"evf-frontend-row\" data-row=\"row_4\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-2\" data-grid=\"grid_1\"><div id=\"evf-3181-field_bNbLl8w9tS-68-container\" class=\"evf-field evf-field-html form-row\" data-field-id=\"bNbLl8w9tS-68\"><div id=\"evf-3181-field_bNbLl8w9tS-68\" class=\"input-text\" conditional_id=\"bNbLl8w9tS-68\"><b>Angonabeiro<\/b>\r\n<p>Rua Kussangula, Estrada Cacuaco Km5 CP 5727 Mulemba \u2013 Cacuaco, Luanda Tel: +244 921 573 320\u202f\u202f | E-mail: info@angonabeiro.co.ao<\/p><\/div><\/div><\/div><div class=\"evf-frontend-grid evf-grid-2\" data-grid=\"grid_2\"><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-3181-field-hp\" class=\"evf-field-label\">Website<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-3181-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"3181\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"186816029\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-3181' value='evf-submit' data-process-text=\"Processing\u2026\" conditional_rules='{&quot;conditional_option&quot;:&quot;hide&quot;,&quot;conditionals&quot;:{&quot;1&quot;:{&quot;1&quot;:{&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;&quot;}}}}' conditional_id='evf-submit-3181'  id=\"evf-submit-3181\" aria-live=\"assertive\">Submit<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div>\n\n\n<style id=\"depicter-821-inline-pre-css\">\n\n.depicter-revert.depicter-821{\n\tbackground-color:#FFF;\n}\n.depicter-821:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-821:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-821:not(.depicter-ready){\n\theight:950px;\n}\n\n}\n<\/style>\n<div id=\"depicter-821\" class=\"depicter depicter-document depicter-revert depicter-821 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-821-section-1\" class=\"depicter-section depicter-821-section-1  fooooter\" data-name=\"Slide 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture id=\"depicter-821-element-2\" class=\"depicter-element depicter-layer depicter-821-element-2\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 1\" data-local-id=\"element-2\" data-offset=\"x:197px;y:127px;origin:tl\" data-tablet-offset=\"x:42px;y:147px;origin:tl\" data-mobile-offset=\"x:122px;y:16px;origin:tl\" data-width=\"116.969px,116.969px,112px\" data-height=\"116.969px,116.969px,112px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/logos_delta_WHT-490490-112x112.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/logos_delta_WHT-490490-224x224.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/logos_delta_WHT-117x117.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/logos_delta_WHT-234x234.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/logos_delta_WHT-490490-117x117.png\" alt=\"\" \/>\n<\/picture>\n<p id=\"depicter-821-element-3\" class=\"depicter-element depicter-layer depicter-821-element-3\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 1\" data-local-id=\"element-3\" data-offset=\"x:520px;y:75px;origin:tl\" data-tablet-offset=\"x:193px;y:137px;origin:tl\" data-mobile-offset=\"x:125px;y:151px;origin:tl\" data-width=\"125px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">CONTACTOS<\/p>\n\n<p id=\"depicter-821-element-6\" class=\"depicter-element depicter-layer depicter-821-element-6\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 4\" data-local-id=\"element-6\" data-offset=\"x:751px;y:75px;origin:tl\" data-tablet-offset=\"x:350px;y:137px;origin:tl\" data-mobile-offset=\"x:96px;y:502px;origin:tl\" data-width=\"167.969px,167.969px,167.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">REVISTA D D D<\/p>\n\n<p id=\"depicter-821-element-8\" class=\"depicter-element depicter-layer depicter-821-element-8\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 5\" data-local-id=\"element-8\" data-offset=\"x:520px;y:112px;origin:tl\" data-tablet-offset=\"x:193px;y:166px;origin:tl\" data-mobile-offset=\"x:126px;y:177px;origin:tl\" data-width=\"189px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Apoio ao Cliente<\/p>\n\n<p id=\"depicter-821-element-9\" class=\"depicter-element depicter-layer depicter-821-element-9\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 6\" data-local-id=\"element-9\" data-offset=\"x:520px;y:136px;origin:tl\" data-tablet-offset=\"x:193px;y:184px;origin:tl\" data-mobile-offset=\"x:127px;y:200px;origin:tl\" data-width=\"176px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">808 20 06 44 *<\/p>\n\n<p id=\"depicter-821-element-10\" class=\"depicter-element depicter-layer depicter-821-element-10\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 7\" data-local-id=\"element-10\" data-offset=\"x:520px;y:153px;origin:tl\" data-tablet-offset=\"x:193px;y:200px;origin:tl\" data-mobile-offset=\"x:113px;y:216px;origin:tl\" data-width=\"170px,136px,136px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">*custo de chamada para a rede fixa nacional<\/p>\n\n<p id=\"depicter-821-element-11\" class=\"depicter-element depicter-layer depicter-821-element-11\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 8\" data-local-id=\"element-11\" data-offset=\"x:520px;y:207px;origin:tl\" data-tablet-offset=\"x:193px;y:235px;origin:tl\" data-mobile-offset=\"x:125px;y:258px;origin:tl\" data-width=\"107.969px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">E-Mail<\/p>\n\n<a href=\"mailto:%20info@gruponabeiro.com\"><p id=\"depicter-821-element-12\" class=\"depicter-element depicter-layer depicter-821-element-12\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 9\" data-local-id=\"element-12\" data-offset=\"x:520px;y:235px;origin:tl\" data-tablet-offset=\"x:193px;y:253px;origin:tl\" data-mobile-offset=\"x:125px;y:276px;origin:tl\" data-width=\"151px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">info@gruponabeiro.com<\/p><\/a>\n\n<a href=\"https:\/\/www.google.com\/maps\/place\/Sede+Delta+Caf\u00e9s+-+Grupo+Nabeiro\/@39.012474,-7.0580982,15z\/data=!4m9!1m2!2m1!1shttps:%2F%2Fprovedoria.gruponabeiro.comAv.+Calouste+Gulbenkian+7370-025+Campo+Maior+Portalegre,+Portugal!3m5!1s0xd16fddb850319db:0x5a8e06dd37192d8d!8m2!3d39.016462!4d-7.065438!16s%2Fg%2F11bbrjnfxy?entry=ttu\"><p id=\"depicter-821-element-13\" class=\"depicter-element depicter-layer depicter-821-element-13\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-13\" data-offset=\"x:520px;y:293px;origin:tl\" data-tablet-offset=\"x:193px;y:295px;origin:tl\" data-mobile-offset=\"x:107px;y:335px;origin:tl\" data-width=\"162px,107.969px,147px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Av. Calouste Gulbenkian<br>7370-025 Campo Maior Portalegre, Portugal<\/p><\/a>\n\n<p id=\"depicter-821-element-14\" class=\"depicter-element depicter-layer depicter-821-element-14\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 11\" data-local-id=\"element-14\" data-offset=\"x:520px;y:266px;origin:tl\" data-tablet-offset=\"x:193px;y:277px;origin:tl\" data-mobile-offset=\"x:125px;y:314px;origin:tl\" data-width=\"107.969px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Morada<\/p>\n\n<a href=\"https:\/\/provedoria.gruponabeiro.com\/\"><p id=\"depicter-821-element-16\" class=\"depicter-element depicter-layer depicter-821-element-16\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 13\" data-local-id=\"element-16\" data-offset=\"x:1221px;y:111px;origin:tl\" data-tablet-offset=\"x:677px;y:168px;origin:tl\" data-mobile-offset=\"x:96px;y:706px;origin:tl\" data-width=\"187px,167px,167px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Aceda aqui ao site da Provedoria do Grupo Nabeiro.<\/p><\/a>\n\n<div id=\"depicter-821-element-26\" class=\"depicter-element depicter-layer depicter-821-element-26\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 3\" data-local-id=\"element-26\" data-offset=\"x:99px;y:384px;origin:tl\" data-tablet-offset=\"x:107px;y:465px;origin:tl\" data-mobile-offset=\"x:-697px;y:811px;origin:tl\" data-width=\"1725px,815px,1725px\" data-height=\"1px,1px,1px\" data-responsive-scale=\"true,,\"><\/div>\n\n<a href=\"https:\/\/deltacafes.com\/politica-de-cookies-delta-cafes\/\" target=\"_blank\"><p id=\"depicter-821-element-31\" class=\"depicter-element depicter-layer depicter-821-element-31\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 19\" data-local-id=\"element-31\" data-offset=\"x:1706px;y:404px;origin:tl\" data-tablet-offset=\"x:913px;y:662px;origin:tl\" data-mobile-offset=\"x:213px;y:878px;origin:tl\" data-width=\"118px,86.9375px,134px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Pol\u00edtica de Cookies<\/p><\/a>\n\n<a href=\"https:\/\/deltacafes.com\/politica-privacidade\/\" target=\"_blank\"><p id=\"depicter-821-element-33\" class=\"depicter-element depicter-layer depicter-821-element-33\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 21\" data-local-id=\"element-33\" data-offset=\"x:1402px;y:404px;origin:tl\" data-tablet-offset=\"x:688px;y:662px;origin:tl\" data-mobile-offset=\"x:213px;y:856px;origin:tl\" data-width=\"142px,108px,156.516px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Pol\u00edtica de Privacidade<\/p><\/a>\n\n<a href=\"https:\/\/whistleblowersoftware.com\/secure\/canaldenunciaGrupoNabeiro\" target=\"_blank\"><p id=\"depicter-821-element-34\" class=\"depicter-element depicter-layer depicter-821-element-34\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 22\" data-local-id=\"element-34\" data-offset=\"x:1222px;y:404px;origin:tl\" data-tablet-offset=\"x:569px;y:662px;origin:tl\" data-mobile-offset=\"x:28px;y:850px;origin:tl\" data-width=\"171px,108px,161px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Canal de \u00c9tica e Conduta<\/p><\/a>\n\n<a href=\"https:\/\/www.livroreclamacoes.pt\/\" target=\"_blank\"><p id=\"depicter-821-element-35\" class=\"depicter-element depicter-layer depicter-821-element-35\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 23\" data-local-id=\"element-35\" data-offset=\"x:1014px;y:404px;origin:tl\" data-tablet-offset=\"x:411px;y:662px;origin:tl\" data-mobile-offset=\"x:28px;y:872px;origin:tl\" data-width=\"208px,147px,149px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Livro de Reclama\u00e7\u00f5es Eletr\u00f3nico<\/p><\/a>\n\n<p id=\"depicter-821-element-36\" class=\"depicter-element depicter-layer depicter-821-element-36\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 24\" data-local-id=\"element-36\" data-offset=\"x:99px;y:404px;origin:tl\" data-tablet-offset=\"x:15px;y:662px;origin:tl\" data-mobile-offset=\"x:28px;y:920px;origin:tl\" data-width=\"546px,257px,375.5px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">\u00a9 2023, Grupo Nabeiro. Todos os direitos reservados.<\/p>\n\n<p id=\"depicter-821-element-38\" class=\"depicter-element depicter-layer depicter-821-element-38\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 11\" data-local-id=\"element-38\" data-offset=\"x:751px;y:118px;origin:tl\" data-tablet-offset=\"x:350px;y:165px;origin:tl\" data-mobile-offset=\"x:96px;y:525px;origin:tl\" data-width=\"217px,167px,167px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\" data-hover-off=\"default\">Descubra a nossa Revista<\/p>\n\n<a href=\"https:\/\/dddelta.com\/\"><p id=\"depicter-821-element-39\" class=\"depicter-element depicter-layer depicter-821-element-39\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 12\" data-local-id=\"element-39\" data-offset=\"x:751px;y:136px;origin:tl\" data-tablet-offset=\"x:350px;y:180px;origin:tl\" data-mobile-offset=\"x:126px;y:541px;origin:tl\" data-width=\"84px,67px,102px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">D DE DELTA<\/p><\/a>\n\n<p id=\"depicter-821-element-40\" class=\"depicter-element depicter-layer depicter-821-element-40\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 13\" data-local-id=\"element-40\" data-offset=\"x:992px;y:74px;origin:tl\" data-tablet-offset=\"x:489px;y:136px;origin:tl\" data-mobile-offset=\"x:95px;y:409px;origin:tl\" data-width=\"167.969px,167.969px,167.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">recrutamento<\/p>\n\n<a href=\"https:\/\/www.gruponabeiro.com\/oportunidades\"><p id=\"depicter-821-element-42\" class=\"depicter-element depicter-layer depicter-821-element-42\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 15\" data-local-id=\"element-42\" data-offset=\"x:992px;y:113px;origin:tl\" data-tablet-offset=\"x:487px;y:165px;origin:tl\" data-mobile-offset=\"x:95px;y:433px;origin:tl\" data-width=\"167px,167px,167px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Conhe\u00e7a as nossas ofertas de emprego ou envie a sua candidatura espont\u00e2nea<\/p><\/a>\n\n<a href=\"https:\/\/deltacafes.com\/termosecondicoes\/\" target=\"_blank\"><p id=\"depicter-821-element-32\" class=\"depicter-element depicter-layer depicter-821-element-32\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 20\" data-local-id=\"element-32\" data-offset=\"x:1558px;y:404px;origin:tl\" data-tablet-offset=\"x:807px;y:662px;origin:tl\" data-mobile-offset=\"x:28px;y:827px;origin:tl\" data-width=\"134px,95px,106px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Termos e Condi\u00e7\u00f5es<\/p><\/a>\n\n<p id=\"depicter-821-element-57\" class=\"depicter-element depicter-layer depicter-821-element-57\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-57\" data-offset=\"x:1221px;y:78px;origin:tl\" data-tablet-offset=\"x:677px;y:122px;origin:tl\" data-mobile-offset=\"x:96px;y:666px;origin:tl\" data-width=\"253.969px,167.969px,167.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Provedoria do cliente<\/p>\n\n<p id=\"depicter-821-element-63\" class=\"depicter-element depicter-layer depicter-821-element-63\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-63\" data-offset=\"x:1221px;y:163px;origin:tl\" data-tablet-offset=\"x:677px;y:226px;origin:tl\" data-mobile-offset=\"x:125px;y:581px;origin:tl\" data-width=\"161px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">ASSIST\u00caNCIA T\u00c9CNICA<\/p>\n\n<p id=\"depicter-821-element-64\" class=\"depicter-element depicter-layer depicter-821-element-64\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 11\" data-local-id=\"element-64\" data-offset=\"x:1221px;y:196px;origin:tl\" data-tablet-offset=\"x:677px;y:282px;origin:tl\" data-mobile-offset=\"x:124px;y:628px;origin:tl\" data-width=\"176px,107.969px,107.969px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">808 20 41 10<\/p>\n\n<div id=\"depicter-821-element-66\" class=\"depicter-element depicter-layer depicter-821-element-66\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 5\" data-local-id=\"element-66\" data-offset=\"x:99px;y:384px;origin:tl\" data-tablet-offset=\"x:107px;y:465px;origin:tl\" data-mobile-offset=\"x:144px;y:572px;origin:tl\" data-width=\"614px,,67px\" data-height=\"0px,,1px\" data-responsive-scale=\"true,,\"><\/div>\n\n<a href=\"https:\/\/www.facebook.com\/DeltaCafes\" target=\"_blank\">\n<picture id=\"depicter-821-element-67\" class=\"depicter-element depicter-layer depicter-821-element-67\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 7\" data-local-id=\"element-67\" data-offset=\"x:1523px;y:198px;origin:tl\" data-mobile-offset=\"x:92px;y:766px;origin:tl\" data-width=\"27.9844px,,30px\" data-height=\"27.9844px,,30px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/face-30x30.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/face-60x60.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/face-28x28.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/face-56x56.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/face-28x28.png\" alt=\"facebook_icon\" \/>\n<\/picture>\n<\/a>\n<a href=\"https:\/\/www.instagram.com\/delta_cafes\/\" target=\"_blank\">\n<picture id=\"depicter-821-element-68\" class=\"depicter-element depicter-layer depicter-821-element-68\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 8\" data-local-id=\"element-68\" data-offset=\"x:1565px;y:193px;origin:tl\" data-mobile-offset=\"x:133px;y:763px;origin:tl\" data-width=\"46.9844px,,44px\" data-height=\"35px,,32px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2024\/06\/CITYPNG.COMHD-White-Instagram-Round-Logo-Icon-PNG-1600x1200-1-44x32.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2024\/06\/CITYPNG.COMHD-White-Instagram-Round-Logo-Icon-PNG-1600x1200-1-88x64.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2024\/06\/CITYPNG.COMHD-White-Instagram-Round-Logo-Icon-PNG-1600x1200-1-47x35.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2024\/06\/CITYPNG.COMHD-White-Instagram-Round-Logo-Icon-PNG-1600x1200-1-94x70.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2024\/06\/CITYPNG.COMHD-White-Instagram-Round-Logo-Icon-PNG-1600x1200-1-47x35.png\" alt=\"instagram_icon\" \/>\n<\/picture>\n<\/a>\n<a href=\"https:\/\/www.youtube.com\/@DeltaCafesYoutube\/videos\" target=\"_blank\">\n<picture id=\"depicter-821-element-69\" class=\"depicter-element depicter-layer depicter-821-element-69\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 9\" data-local-id=\"element-69\" data-offset=\"x:1621px;y:195px;origin:tl\" data-mobile-offset=\"x:187px;y:763px;origin:tl\" data-width=\"31px,,32px\" data-height=\"31px,,32px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/you-32x32.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/you-64x64.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/you-31x31.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/you-62x62.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/you-31x31.png\" alt=\"youtube_icon\" \/>\n<\/picture>\n<\/a>\n<a href=\"https:\/\/www.linkedin.com\/company\/delta-cafes\" target=\"_blank\">\n<picture id=\"depicter-821-element-70\" class=\"depicter-element depicter-layer depicter-821-element-70\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 10\" data-local-id=\"element-70\" data-offset=\"x:1669px;y:196px;origin:tl\" data-mobile-offset=\"x:236px;y:763px;origin:tl\" data-width=\"27.9844px,,31px\" data-height=\"27.9844px,,31px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/linkedin-31x31.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/linkedin-62x62.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/linkedin-28x28.png, https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/linkedin-56x56.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/linkedin-28x28.png\" alt=\"linkedin_icon\" \/>\n<\/picture>\n<\/a><\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/deltacafes.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-821',\n\t\t{\"width\":[\"1920\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"950\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/deltacafes.com\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":false,\"touchSwipe\":false,\"keyboard\":false,\"useWatermark\":false}\n\t);\n});\n<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":186816029,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"footnotes":""},"class_list":["post-3186","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ANGOLA - Delta Caf\u00e9s<\/title>\n<meta name=\"description\" content=\"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deltacafes.com\/en\/angola-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANGOLA - Delta Caf\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deltacafes.com\/en\/angola-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Delta Caf\u00e9s\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T11:33:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deltacafes.com\\\/angola-2\\\/\",\"url\":\"https:\\\/\\\/deltacafes.com\\\/angola-2\\\/\",\"name\":\"ANGOLA - Delta Caf\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#website\"},\"datePublished\":\"2023-09-01T11:05:19+00:00\",\"dateModified\":\"2024-07-12T11:33:03+00:00\",\"description\":\"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deltacafes.com\\\/angola-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deltacafes.com\\\/angola-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deltacafes.com\\\/angola-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/deltacafes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANGOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#website\",\"url\":\"https:\\\/\\\/deltacafes.com\\\/\",\"name\":\"Delta Caf\u00e9s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deltacafes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#organization\",\"name\":\"Delta Coffee House Experience\",\"url\":\"https:\\\/\\\/deltacafes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deltacafes.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-logo-delta.png\",\"contentUrl\":\"https:\\\/\\\/deltacafes.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-logo-delta.png\",\"width\":512,\"height\":512,\"caption\":\"Delta Coffee House Experience\"},\"image\":{\"@id\":\"https:\\\/\\\/deltacafes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANGOLA - Delta Caf\u00e9s","description":"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deltacafes.com\/en\/angola-2\/","og_locale":"en_US","og_type":"article","og_title":"ANGOLA - Delta Caf\u00e9s","og_description":"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.","og_url":"https:\/\/deltacafes.com\/en\/angola-2\/","og_site_name":"Delta Caf\u00e9s","article_modified_time":"2024-07-12T11:33:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deltacafes.com\/angola-2\/","url":"https:\/\/deltacafes.com\/angola-2\/","name":"ANGOLA - Delta Caf\u00e9s","isPartOf":{"@id":"https:\/\/deltacafes.com\/#website"},"datePublished":"2023-09-01T11:05:19+00:00","dateModified":"2024-07-12T11:33:03+00:00","description":"Departamento da Delta Caf\u00e9s em Angola. Todos os contactos dispon\u00edveis na p\u00e1gina do site. Contacte-nos agora.","breadcrumb":{"@id":"https:\/\/deltacafes.com\/angola-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deltacafes.com\/angola-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/deltacafes.com\/angola-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/deltacafes.com\/"},{"@type":"ListItem","position":2,"name":"ANGOLA"}]},{"@type":"WebSite","@id":"https:\/\/deltacafes.com\/#website","url":"https:\/\/deltacafes.com\/","name":"Delta Caf\u00e9s","description":"","publisher":{"@id":"https:\/\/deltacafes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deltacafes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/deltacafes.com\/#organization","name":"Delta Coffee House Experience","url":"https:\/\/deltacafes.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/deltacafes.com\/#\/schema\/logo\/image\/","url":"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/cropped-logo-delta.png","contentUrl":"https:\/\/deltacafes.com\/wp-content\/uploads\/2023\/08\/cropped-logo-delta.png","width":512,"height":512,"caption":"Delta Coffee House Experience"},"image":{"@id":"https:\/\/deltacafes.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PdvybT-Po","_links":{"self":[{"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/pages\/3186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/users\/186816029"}],"replies":[{"embeddable":true,"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/comments?post=3186"}],"version-history":[{"count":4,"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/pages\/3186\/revisions"}],"predecessor-version":[{"id":3814,"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/pages\/3186\/revisions\/3814"}],"wp:attachment":[{"href":"https:\/\/deltacafes.com\/en\/wp-json\/wp\/v2\/media?parent=3186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}